{"id":307,"date":"2015-09-24T10:20:02","date_gmt":"2015-09-24T08:20:02","guid":{"rendered":"http:\/\/www.liberabg.it\/l\/2015\/09\/we-care-nuovo-anno-di-incontri-per-i-giovani\/"},"modified":"2015-09-24T10:20:02","modified_gmt":"2015-09-24T08:20:02","slug":"we-care-nuovo-anno-di-incontri-per-i-giovani","status":"publish","type":"post","link":"https:\/\/www.liberabg.it\/index.php\/2015\/09\/we-care-nuovo-anno-di-incontri-per-i-giovani\/","title":{"rendered":"WE CARE, nuovo anno di incontri per i giovani"},"content":{"rendered":"<p><a target=\"_blank\" href=\"http:\/\/www.scuolawecare.it\/pdf\/depliant_Scuola_Formazione_2015_2016.pdf\"><img fetchpriority=\"high\" decoding=\"async\" class=\" alignleft size-full wp-image-306\" src=\"http:\/\/www.liberabg.it\/l\/wp-content\/uploads\/2015\/09\/2015.16_wecare.jpg\" width=\"184\" height=\"331\" alt=\"2015.16_wecare\" style=\"margin: 7px; float: left;\" srcset=\"https:\/\/www.liberabg.it\/l\/wp-content\/uploads\/2015\/09\/2015.16_wecare.jpg 184w, https:\/\/www.liberabg.it\/l\/wp-content\/uploads\/2015\/09\/2015.16_wecare-167x300.jpg 167w\" sizes=\"(max-width: 184px) 100vw, 184px\" \/><\/a> <\/p>\n<h1>Una scuola plurale e territoriale<\/h1>\n<p>WE CARE \u00e8 sempre stato pluralista (perch\u00e9 promosso da varie realt\u00e0 sociali e culturali)e decentrato (gli incontri si sono svolti in diverse sedi e quartieri della citt\u00e0).&nbsp;Dallo scorso anno \u00e8 diventato anche territoriale perch\u00e9 la Scuola promuove o direttamente organizza,insieme a realt\u00e0 sociali o istituzionali dei quartieri o dei paesi, percorsi di formazione alla politica.&nbsp;<\/p>\n<p>Consulta <span style=\"font-size: 12pt;\"><a target=\"_blank\" href=\"http:\/\/www.scuolawecare.it\/pdf\/depliant_Scuola_Formazione_2015_2016.pdf\">il VOLANTINO<\/a><\/span> per informazioni sugli incontri e iscrizione.<\/p>\n<p><a href=\"http:\/\/www.scuolawecare.it\/\">www.scuolawecare.it<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una scuola plurale e territoriale WE CARE \u00e8 sempre stato pluralista (perch\u00e9 promosso da varie realt\u00e0 sociali e culturali)e decentrato (gli incontri si sono svolti in diverse sedi e quartieri della citt\u00e0).&nbsp;Dallo scorso anno \u00e8 diventato anche territoriale perch\u00e9 la Scuola promuove o direttamente organizza,insieme a realt\u00e0 sociali o istituzionali &hellip;<\/p>\n","protected":false},"author":1,"featured_media":306,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[13],"tags":[],"class_list":["post-307","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-libera-informazione"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.liberabg.it\/l\/wp-content\/uploads\/2015\/09\/2015.16_wecare.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7YFQD-4X","_links":{"self":[{"href":"https:\/\/www.liberabg.it\/index.php\/wp-json\/wp\/v2\/posts\/307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.liberabg.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.liberabg.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.liberabg.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.liberabg.it\/index.php\/wp-json\/wp\/v2\/comments?post=307"}],"version-history":[{"count":0,"href":"https:\/\/www.liberabg.it\/index.php\/wp-json\/wp\/v2\/posts\/307\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.liberabg.it\/index.php\/wp-json\/wp\/v2\/media\/306"}],"wp:attachment":[{"href":"https:\/\/www.liberabg.it\/index.php\/wp-json\/wp\/v2\/media?parent=307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.liberabg.it\/index.php\/wp-json\/wp\/v2\/categories?post=307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.liberabg.it\/index.php\/wp-json\/wp\/v2\/tags?post=307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}